{"id":5509,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/bacardi-brasil-amplia-quiosque-da-marca-no-rio-de-janeiro\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"bacardi-brasil-amplia-quiosque-da-marca-no-rio-de-janeiro","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/bacardi-brasil-amplia-quiosque-da-marca-no-rio-de-janeiro\/","title":{"rendered":"Bacardi Brasil amplia quiosque da marca no Rio de Janeiro"},"content":{"rendered":"<p>A Bacard\u00ed Brasil reinaugurou o quiosque da marca, localizado na orla de Copacabana, no Rio de Janeiro. O Quiosque Bacard\u00ed, lan\u00e7ado em 11 de abril para se tornar a vitrine da marca no Rio de Janeiro, agora conta com um balc\u00e3o de drinques com uma vista privilegiada para o mar. O n\u00famero de lugares tamb\u00e9m aumentou de 84 para 140 lugares.<br \/>\nO Quiosque Bacardi oferece um card\u00e1pio bastante variado, com drinques feitos com os produtos da empresa. A carta de drinques foi desenvolvida pelo Alex Mesquista, profissional eleito como o melhor bartender do ano de 2012 pela Veja Rio.<br \/>\nS\u00e3o oferecidas 35 op\u00e7\u00f5es de drinques, entre eles Bacardi Mojito, Bacardi Daiquiri Strawberry, Big Fresh Bacard\u00ed Big Apple, Grey Goose Tropical Day, Grey Goose Guava Refresh, Grey Goose Spirit of Beach, Amarula on the Rocks e Martirinha com lim\u00e3o Tahiti.<\/p>\n<p>&quot;Consideramos o Rio de Janeiro como um mercado diferenciado e queremos aumentar ainda mais a visibilidade da marca Bacard\u00ed na cidade carioca. Reinauguramos o Quiosque Bacard\u00ed para proporcionar um espa\u00e7o mais amplo e um divertido ponto de encontro para os nossos consumidores. O Quiosque Bacard\u00ed tem tudo para se tornar uma refer\u00eancia em coquetelaria e experi\u00eancia da marca.&quot;, refor\u00e7a Fabio Di Giammarco.<\/p>\n<p>O vice-presidente da concession\u00e1ria Orla Rio, Jo\u00e3o Marcello Barreto, refor\u00e7a: &quot;Essa amplia\u00e7\u00e3o deve trazer ainda mais conforto para os clientes do quiosque. Tornar a orla do Rio ainda mais bela e atrativa para todos os frequentadores \u00e9 o nosso principal objetivo. \u00c9 um ganho para o carioca e para os turistas&quot;.<\/p>\n<p>Atualmente, o Quiosque Bacard\u00ed est\u00e1 personalizado com BACARD\u00cd BIG APPLE, rum com sabor de ma\u00e7\u00e3 verde que virou um fen\u00f4meno de vendas na cidade carioca. A perfeita combina\u00e7\u00e3o de BACARD\u00cd BIG APPLE, com gelo e refrigerante de soda e a sinergia do produto com o estilo de vida carioca garantiram o sucesso do produto na cidade.<\/p>\n<p>Fonte: Cidade Marketing<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Bacard\u00ed Brasil reinaugurou o quiosque da marca, localizado na orla de Copacabana, no Rio de Janeiro. O Quiosque Bacard\u00ed, lan\u00e7ado em 11 de abril para se tornar a vitrine da marca no Rio de Janeiro, agora conta com um balc\u00e3o de drinques com uma vista privilegiada para o mar. O n\u00famero de lugares tamb\u00e9m &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/bacardi-brasil-amplia-quiosque-da-marca-no-rio-de-janeiro\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Bacardi Brasil amplia quiosque da marca no Rio de Janeiro&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5509","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5509"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5509\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}