{"id":5582,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/marketing-atrapalhado-ou-miopia-em-marketing\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"marketing-atrapalhado-ou-miopia-em-marketing","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/marketing-atrapalhado-ou-miopia-em-marketing\/","title":{"rendered":"Marketing atrapalhado ou miopia em Marketing?"},"content":{"rendered":"<p>No livro \u201cComo Afundar Sua Empresa\u201d os autores Bruce Nash e Alla Zullo fazem um levantamento dos principais erros de marketing que provocaram preju\u00edzos a grandes organiza\u00e7\u00f5es, mostrando uma cole\u00e7\u00e3o de promo\u00e7\u00f5es mal calculadas e lan\u00e7amentos fracassados, causados pelas trapalhadas de seus profissionais de marketing.<\/p>\n<p>Uma das hist\u00f3rias mais curiosas ocorreu durante o improviso no lan\u00e7amento de uma ra\u00e7\u00e3o canina. A ag\u00eancia de propaganda promoveu um almo\u00e7o com a imprensa, quando a referida ra\u00e7\u00e3o foi servida a um c\u00e3o da ra\u00e7a collie posicionado ao lado do presidente da empresa. <\/p>\n<p>Por\u00e9m, o c\u00e3o sequer olhou para a comida e, diante disso, o executivo acabou limpando o prato do animal. No dia seguinte alguns jornais estampavam a seguinte manchete: \u201cO Presidente Comeu, Mas o Cachorro N\u00e3o\u201d. A ag\u00eancia, claro, acabou perdendo a conta dessa empresa.<\/p>\n<p>Outra hist\u00f3ria apontada no livro exp\u00f5e o risco de vincular a credibilidade de uma determinada marca a uma garota propaganda. Foi o que aconteceu com a Procter &#038; Gamble (P&#038;G) ao vincular a imagem do seu produto (sab\u00e3o em p\u00f3 IVORY) \u00e0 modelo de ar angelical Marilyn Brigss. <\/p>\n<p>Tudo corria bem at\u00e9 o ano de 1973, quando a referida atriz estreou em um filme porn\u00f4 e a P&#038;G teve que recolher milh\u00f5es de pacotes do seu sab\u00e3o das prateleiras dos supermercados americanos.<\/p>\n<p>Outra trapalhada aconteceu com a antiga companhia a\u00e9rea \u2013 Braniff. A fim de atrair o p\u00fablico hisp\u00e2nico eles traduziram de forma equivocada seu an\u00fancio, o qual convidava os passageiros a viajar \u201cem pelos\u201d (\u201cen cueros\u201d, referindo-se ao revestimento das poltronas) e, pior ainda, sua propaganda prometia \u201coito cent\u00edmetros a mais\u201d referindo-se ao maior espa\u00e7o entre os bancos de seus avi\u00f5es. Claro que o p\u00fablico detestou.<\/p>\n<p>Produtos inovadores mal formulados tamb\u00e9m foram relatados no livro, referindo-se ao lan\u00e7amento de um suco de frutas natural pela empresa Adams Natural Beverage. <\/p>\n<p>Ap\u00f3s alguns meses do seu lan\u00e7amento as latas de suco come\u00e7aram a \u201cexplodir\u201d nas prateleiras, pois os marqueteiros da empresa n\u00e3o previram que a bebida poderia fermentar, provocando o incha\u00e7o nas latas.<\/p>\n<p>Por outro lado, algumas institui\u00e7\u00f5es de prest\u00edgio internacional \u2013 Boston Consulting Group e Strategic Planning, por exemplo \u2013 acreditavam que, ao dominarem determinadas parcelas de mercado, as empresas teriam garantido o sucesso de seus produtos.<\/p>\n<p>Mas, conforme Theodore Levitt isso n\u00e3o verdade. Em seu artigo \u201cMiopia em Marketing\u201d Levitt mostrou a pouca vis\u00e3o dos profissionais de marketing em prever as varia\u00e7\u00f5es e de como o dom\u00ednio de um mercado n\u00e3o seriam garantias contra os fracassos.<\/p>\n<p>Em 1920 o carv\u00e3o contribu\u00eda com 77% da energia consumida nos EUA e, no entanto, os empres\u00e1rios do setor n\u00e3o reconheceram a import\u00e2ncia do petr\u00f3leo como fonte de energia. Em 1967 apenas 23% da energia eram oriunda do carv\u00e3o e, em consequ\u00eancia disso, muitas minas foram fechadas e v\u00e1rias empresas desapareceram.<\/p>\n<p>Levitt informa que o petr\u00f3leo era usado inicialmente como base para produtos medicinais, embora as l\u00e2mpadas de querosene tenham provocado o primeiro crescimento da ind\u00fastria. Ao surgir a l\u00e2mpada incandescente tornou-se claro que a ilumina\u00e7\u00e3o n\u00e3o precisaria utilizar o querosene, embora as empresas petrol\u00edferas nada tenham feito.<\/p>\n<p>Levitt nos d\u00e1 conta do desenvolvimento do aquecimento a carv\u00e3o nos EUA, o qual tornou o aquecimento a querosene ultrapassado. Novamente, a ind\u00fastria petrol\u00edfera n\u00e3o se mexeu, embora tenha sido salva pelo motor a gasolina \u2013 inventado fora da ind\u00fastria \u2013 que lhetrouxe outro ciclo de crescimento.<\/p>\n<p>Quando o mercado novamente mostrou sinais de recupera\u00e7\u00e3o veio a guerra \u2013 com sua enorme demanda de gasolina para a avia\u00e7\u00e3o \u2013 e manteve-se a expans\u00e3o da ind\u00fastria. <\/p>\n<p>Enquanto isso, as instala\u00e7\u00f5es de aquecimento a \u00f3leo perdiam mercado para as instala\u00e7\u00f5es a g\u00e1s natural, as quais prov\u00eam de po\u00e7os que n\u00e3o eram propriedade das empresas petrol\u00edferas. Elas tinham a tecnologia da produ\u00e7\u00e3o em aquecimento de edif\u00edcios, mas n\u00e3o se interessaram pelo g\u00e1s natural porque j\u00e1 possu\u00edam o \u00f3leo. Mais tarde, algumas empresas de petr\u00f3leo compraram o controle de algumas empresas de g\u00e1s, mas tiveram que pagar bem caro por isso.<\/p>\n<p>Outro setor analisado por Levitt foi o mercado de alimentos, dominado naquela \u00e9poca pelas groceries \u2013 semelhantes aos nossos antigos armaz\u00e9ns. Talvez esse tenha sido o melhor exemplo de miopia analisado por Levitt, pois esse setorignorou o aparecimento dos supermercados em 1930 e, na sua conven\u00e7\u00e3o anual de 1936, concluiu que \u201cn\u00e3o havia nada a temer\u201d. Deu no que deu.<\/p>\n<p>Fonte: Administradores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No livro \u201cComo Afundar Sua Empresa\u201d os autores Bruce Nash e Alla Zullo fazem um levantamento dos principais erros de marketing que provocaram preju\u00edzos a grandes organiza\u00e7\u00f5es, mostrando uma cole\u00e7\u00e3o de promo\u00e7\u00f5es mal calculadas e lan\u00e7amentos fracassados, causados pelas trapalhadas de seus profissionais de marketing. Uma das hist\u00f3rias mais curiosas ocorreu durante o improviso no &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/marketing-atrapalhado-ou-miopia-em-marketing\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Marketing atrapalhado ou miopia em Marketing?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5582","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5582"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5582\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}