{"id":5592,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/embraer-cria-o-catalogo-que-voa\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"embraer-cria-o-catalogo-que-voa","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/embraer-cria-o-catalogo-que-voa\/","title":{"rendered":"Embraer cria o cat\u00e1logo que \u201cvoa\u201d"},"content":{"rendered":"<p>A Embraer \u00e9 uma construtora de jatos particulares, e, para lan\u00e7ar o seu mais novo e exclusivo modelo, o Linage 1000, a empresa criou um cat\u00e1logo de apresenta\u00e7\u00e3o muito inovador, chamado \u201cEmbraer Flying Book\u201d.<\/p>\n<p>Trata-se de um livro que \u201cflutua\u201d em sua pr\u00f3pria base, dando a impress\u00e3o de que o cat\u00e1logo realmente voa, j\u00e1 passando uma \u00f3tima imagem do novo jato antes mesmo de ser analisado.<\/p>\n<p>Na produ\u00e7\u00e3o dos cat\u00e1logos, foram inseridos \u00edm\u00e3s tanto nele quanto em sua base, fazendo com que ele levite, surpreendendo a todos os potenciais clientes da Embraer escolhidos a dedo para receberam esta mala direta.<\/p>\n<p>Fonte: Promoview<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Embraer \u00e9 uma construtora de jatos particulares, e, para lan\u00e7ar o seu mais novo e exclusivo modelo, o Linage 1000, a empresa criou um cat\u00e1logo de apresenta\u00e7\u00e3o muito inovador, chamado \u201cEmbraer Flying Book\u201d. Trata-se de um livro que \u201cflutua\u201d em sua pr\u00f3pria base, dando a impress\u00e3o de que o cat\u00e1logo realmente voa, j\u00e1 passando &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/embraer-cria-o-catalogo-que-voa\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Embraer cria o cat\u00e1logo que \u201cvoa\u201d&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5592","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5592"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}