{"id":5641,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/afinal-como-se-administra\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"afinal-como-se-administra","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/afinal-como-se-administra\/","title":{"rendered":"Afinal, como se administra?"},"content":{"rendered":"<p>A administra\u00e7\u00e3o \u00e9 uma ci\u00eancia humana e, n\u00e3o sendo uma ci\u00eancia exata, suas t\u00e9cnicas, pr\u00e1ticas e experi\u00eancias s\u00e3o bem variadas. Essa afirma\u00e7\u00e3o \u00e9 f\u00e1cil de ser comprovada na pr\u00e1tica de trabalho de in\u00fameras pessoas que, pelo menos uma vez, j\u00e1 trocaram de emprego. Um empres\u00e1rio (administrador) jamais gerencia sua empresa da mesma maneira que outro, ele gerencia e administra da sua maneira, mesmo que tenha feito a mesma faculdade com os mesmos professores e ainda tenham sido estes colegas de classe.<\/p>\n<p>Cada pessoa tem o seu jeito, tem o seu estilo, isso n\u00e3o muda. \u00c9 sabido que a pr\u00f3pria ci\u00eancia da Administra\u00e7\u00e3o, suas teorias e experi\u00eancias mudam de acordo com a cultura e evolu\u00e7\u00e3o da sociedade. Se isso acontece, porque ter\u00edamos ent\u00e3o que estudar Administra\u00e7\u00e3o?<\/p>\n<p>Na verdade esse estudo nos nivela a um padr\u00e3o de teorias e experi\u00eancias bem sucedidas e que seu conhecimento nos coloca com mais condi\u00e7\u00f5es para decidirmos e fazermos um futuro melhor.<br \/>\nPara melhor entender utilizo um conceito mais simples de Administra\u00e7\u00e3o. Respeitando e compilando os conceitos de outros autores, eu resumiria que Administra\u00e7\u00e3o \u00e9: &quot;Tomar decis\u00f5es, atrav\u00e9s das pessoas para os melhores resultados&quot;. Nesse conceito destaco tr\u00eas palavras chave para se considerar a administra\u00e7\u00e3o de necessidades de uma empresa ou at\u00e9 mesmo de nossas vidas: decis\u00f5es, pessoas e resultados.<\/p>\n<p>Tomar decis\u00f5es \u2013 eis a\u00ed uma das coisas mais dif\u00edceis de fazer, ainda mais quando se trata de pessoas \u2013 \u00e9 o mais determinante. Imagine voc\u00ea ter que decidir entre duas pessoas para contratar em sua empresa, por exemplo, o cargo seria de vendedor t\u00e9cnico de m\u00e1quinas, sendo subordinado a um gerente de vendas. Uma delas demonstrou que tem todo o potencial t\u00e9cnico que voc\u00ea necessita, mas voc\u00ea ficou com d\u00favida sobre sua postura profissional e bom relacionamento para trabalhar no grupo. A outra pessoa se mostrou bem mais desenvolvida na postura e relacionamentos, mas n\u00e3o tanta habilidade ou potencial t\u00e9cnico. Qual pessoa deve ser contratada?<\/p>\n<p>O mundo sem pessoas seria morto, ou seja, nem existiria. Viver e se fazer vivo significa ter uma rela\u00e7\u00e3o forte com outras pessoas, ou seja, criar um bom relacionamento. A administra\u00e7\u00e3o de sua vida ou empresa depende basicamente das pessoas com que voc\u00ea convive ou trabalha. Administrar, desta maneira, se torna algo muito complexo, mas verdadeiramente humano. Afinal, voc\u00ea administra \u00e9 para as pessoas, e n\u00e3o para coisas materiais.<\/p>\n<p>Basicamente administro em busca dos melhores resultados. Se voc\u00ea n\u00e3o pensa assim nem se preocupe em administrar ou entender melhor a ci\u00eancia da Administra\u00e7\u00e3o, ela n\u00e3o tem sentido sem resultados. O resultado de forma pessoal pode ser uma melhora no amor em fam\u00edlia, uma melhora na sua sa\u00fade, por exemplo, balanceando sua alimenta\u00e7\u00e3o, as atividades f\u00edsicas que faz, etc. Mas resultado positivo mesmo \u00e9 sair de uma situa\u00e7\u00e3o atual para uma melhor.<\/p>\n<p>Conclu\u00edmos ent\u00e3o que Administrar tem de ser, necessariamente, uma atividade baseada em projetos e a\u00e7\u00f5es que d\u00eaem as melhores condi\u00e7\u00f5es para a tomada de DECIS\u00c3O, as melhores condi\u00e7\u00f5es para o bom relacionamento entre as PESSOAS, e da\u00ed ent\u00e3o, a coordena\u00e7\u00e3o de todas as a\u00e7\u00f5es para alcance dos melhores RESULTADOS.<\/p>\n<p>Por fim lembre ainda algo important\u00edssimo da \u00e1rea do Marketing: os resultados devem ser mais humanos, devem estar focados nas necessidades das pessoas. Pensando assim, nas pessoas, os MELHORES RESULTADOS ser\u00e3o conseq\u00fc\u00eancia. Portanto, estude mais, administre de seu jeito e estilo, mas entenda e valorize as pessoas, \u00e9 voc\u00ea quem decide seu futuro e resultados! <\/p>\n<p>Fonte: Administradores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A administra\u00e7\u00e3o \u00e9 uma ci\u00eancia humana e, n\u00e3o sendo uma ci\u00eancia exata, suas t\u00e9cnicas, pr\u00e1ticas e experi\u00eancias s\u00e3o bem variadas. Essa afirma\u00e7\u00e3o \u00e9 f\u00e1cil de ser comprovada na pr\u00e1tica de trabalho de in\u00fameras pessoas que, pelo menos uma vez, j\u00e1 trocaram de emprego. Um empres\u00e1rio (administrador) jamais gerencia sua empresa da mesma maneira que outro, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/afinal-como-se-administra\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Afinal, como se administra?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5641","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5641"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5641\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}