{"id":5664,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/jack-daniels-coloca-camaro-a-disposicao-de-clientes\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"jack-daniels-coloca-camaro-a-disposicao-de-clientes","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/jack-daniels-coloca-camaro-a-disposicao-de-clientes\/","title":{"rendered":"Jack Daniel\u2019s coloca Camaro \u00e0 disposi\u00e7\u00e3o de clientes"},"content":{"rendered":"<p>Para promover a mixologia e as combina\u00e7\u00f5es Jack &#038; Cola, Jack &#038; Citrus e MaracuJack, tem in\u00edcio a segunda edi\u00e7\u00e3o da Jack Time, plataforma desenvolvida pela Brow-Forman, dona da marca Jack Daniel\u2019s.<\/p>\n<p>A a\u00e7\u00e3o de marketing promocional acontece de julho a janeiro em dezenas de bares de Belo Horizonte (MG), Campinas (SP), Curitiba (PR), Fortaleza (CE), Recife (PE), Ribeir\u00e3o Preto (SP), Rio de Janeiro (RJ), S\u00e3o Carlos (SP) e S\u00e3o Paulo (SP).<br \/>\nOs estabelecimentos v\u00e3o oferecer releituras dos drinques feitos com Jack Daniel\u2019s e tamb\u00e9m apresentar novas vers\u00f5es de mixologia com o produto.<\/p>\n<p>O investimento em mixologia faz parte da estrat\u00e9gia da companhia de bebidas para rejuvenescer a marca \u2013 que ter\u00e1 uma nova garrafa a partir do ano que vem \u2013 e atingir um novo p\u00fablico para o produto: consumidores mais jovens e mulheres.<br \/>\nAl\u00e9m da \u201cDrink Route\u201d, Jack Time conta com duas promo\u00e7\u00f5es e quizzes que render\u00e3o pr\u00eamios na hora para o p\u00fablico nos bares e para um grupo especial no aplicativo para celulares WhatsApp.<\/p>\n<p>A a\u00e7\u00e3o promocional de perguntas e respostas pretende gerar engajamento e dar a oportunidade para os clientes que comprarem um \u201cJack Drink\u201d ou uma garrafa da bebida de voltarem para casa com camisetas, copos e mochilas.<\/p>\n<p>Na linha do consumo respons\u00e1vel, Jack Time levar\u00e1 paras as ruas um modelo Camaro para oferecer carona aos consumidores. Ganhar\u00e1 a volta para casa o primeiro consumidor que comprar uma garrafa fechada do produto no bar participante.<\/p>\n<p>Tamb\u00e9m ser\u00e3o distribu\u00eddas caronas de ida e volta para baladas por meio de concursos culturais realizados na p\u00e1gina da marca no Facebook. As a\u00e7\u00f5es de marketing promocional com o Camaro Jack Daniel\u2019s abrangem Fortaleza (CE), S\u00e3o Paulo (SP) e Rio de Janeiro (RJ).<br \/>\nAl\u00e9m da \u201cDrink Route\u201d, Jack Time conta com duas promo\u00e7\u00f5es e quizzes que render\u00e3o pr\u00eamios na hora para o p\u00fablico nos bares e para um grupo especial no aplicativo para celulares WhatsApp.<\/p>\n<p>A a\u00e7\u00e3o promocional de perguntas e respostas pretende gerar engajamento e dar a oportunidade para os clientes que comprarem um \u201cJack Drink\u201d ou uma garrafa da bebida de voltarem para casa com camisetas, copos e mochilas.<\/p>\n<p>Na linha do consumo respons\u00e1vel, Jack Time levar\u00e1 paras as ruas um modelo Camaro para oferecer carona aos consumidores. Ganhar\u00e1 a volta para casa o primeiro consumidor que comprar uma garrafa fechada do produto no bar participante.<\/p>\n<p>Tamb\u00e9m ser\u00e3o distribu\u00eddas caronas de ida e volta para baladas por meio de concursos culturais realizados na p\u00e1gina da marca no Facebook. As a\u00e7\u00f5es de marketing promocional com o Camaro Jack Daniel\u2019s abrangem Fortaleza (CE), S\u00e3o Paulo (SP) e Rio de Janeiro (RJ).<\/p>\n<p>Fonte: Promoview<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para promover a mixologia e as combina\u00e7\u00f5es Jack &#038; Cola, Jack &#038; Citrus e MaracuJack, tem in\u00edcio a segunda edi\u00e7\u00e3o da Jack Time, plataforma desenvolvida pela Brow-Forman, dona da marca Jack Daniel\u2019s. A a\u00e7\u00e3o de marketing promocional acontece de julho a janeiro em dezenas de bares de Belo Horizonte (MG), Campinas (SP), Curitiba (PR), Fortaleza &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/jack-daniels-coloca-camaro-a-disposicao-de-clientes\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Jack Daniel\u2019s coloca Camaro \u00e0 disposi\u00e7\u00e3o de clientes&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5664","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5664"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5664\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}