{"id":5667,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/marca-americana-aposta-em-cafe-sabor-bacon\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"marca-americana-aposta-em-cafe-sabor-bacon","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/marca-americana-aposta-em-cafe-sabor-bacon\/","title":{"rendered":"Marca americana aposta em caf\u00e9 sabor bacon"},"content":{"rendered":"<p>Bacon e caf\u00e9, dois ingredientes essenciais na vida de muita gente.  E a\u00ed, quando voc\u00ea acha que j\u00e1 viu de tudo, vem a marca de caf\u00e9 americana Boca Java e lan\u00e7a um produto que vai agradar e saciar a vontade dos amantes de toucinho nas refei\u00e7\u00f5es matinais: o Bacon Coffee.<\/p>\n<p>S\u00e3o gr\u00e3os de caf\u00e9 gourmet 100% ar\u00e1bicos adicionados de sabor. A empresa tamb\u00e9m vende caf\u00e9 sabor banana, caramelo, chocolate branco com framboesa e muitos outros. Por\u00e9m, o produto sabor bacon \u00e9 o top seller, ou seja, o mais vendido da categoria do portf\u00f3lio.<\/p>\n<p>Fonte: Promoview<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bacon e caf\u00e9, dois ingredientes essenciais na vida de muita gente. E a\u00ed, quando voc\u00ea acha que j\u00e1 viu de tudo, vem a marca de caf\u00e9 americana Boca Java e lan\u00e7a um produto que vai agradar e saciar a vontade dos amantes de toucinho nas refei\u00e7\u00f5es matinais: o Bacon Coffee. S\u00e3o gr\u00e3os de caf\u00e9 gourmet &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/marca-americana-aposta-em-cafe-sabor-bacon\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Marca americana aposta em caf\u00e9 sabor bacon&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5667","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5667"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5667\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}