{"id":5673,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/correios-lanca-selo-comemorativo-em-homenagem-ao-papa-francisco\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"correios-lanca-selo-comemorativo-em-homenagem-ao-papa-francisco","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/correios-lanca-selo-comemorativo-em-homenagem-ao-papa-francisco\/","title":{"rendered":"Correios lan\u00e7a selo comemorativo em homenagem ao Papa Francisco"},"content":{"rendered":"<p>Na ter\u00e7a-feira (23), os Correios colocam em circula\u00e7\u00e3o o selo que celebra a visita do Papa Francisco ao Brasil durante a Jornada Mundial da Juventude Rio2013 (JMJ Rio2013). O lan\u00e7amento ser\u00e1 realizado na praia de Copacabana ap\u00f3s a missa de abertura, que ser\u00e1 celebrada \u00e0s 19h30 pelo arcebispo do Rio de Janeiro, Dom Orani Jo\u00e3o Tempesta.<\/p>\n<p>O selo traz, em primeiro plano, a imagem do Papa no gesto de emiss\u00e3o de ben\u00e7\u00e3o. Ao fundo, a representa\u00e7\u00e3o da vista da Ba\u00eda de Guanabara e, \u00e0 esquerda, o monumento do Cristo Redentor, s\u00edmbolo escolhido para a 28\u00aa Edi\u00e7\u00e3o da Jornada Mundial da Juventude.<\/p>\n<p>As cores verde, azul e amarela, usadas para compor a marca do evento, est\u00e3o presentes na natureza da cidade e na bandeira brasileira. Acima da bandeira, a logomarca oficial da JMJ Rio2013. A arte do selo \u00e9 de Fernando Lopes, que utilizou a t\u00e9cnica de aquarela sobre papel na confec\u00e7\u00e3o da ilustra\u00e7\u00e3o.<\/p>\n<p>Ser\u00e3o emitidos 1,2 milh\u00e3o de selos, comercializados a R$ 1,80 cada. As pe\u00e7as poder\u00e3o ser adquiridas pela loja virtual (www.correios.com.br\/correiosonline), pela Ag\u00eancia de Vendas a Dist\u00e2ncia (centralvendas@correios.com.br) ou nas ag\u00eancias dos Correios.<\/p>\n<p>Fonte: Cidade MArketing<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na ter\u00e7a-feira (23), os Correios colocam em circula\u00e7\u00e3o o selo que celebra a visita do Papa Francisco ao Brasil durante a Jornada Mundial da Juventude Rio2013 (JMJ Rio2013). O lan\u00e7amento ser\u00e1 realizado na praia de Copacabana ap\u00f3s a missa de abertura, que ser\u00e1 celebrada \u00e0s 19h30 pelo arcebispo do Rio de Janeiro, Dom Orani Jo\u00e3o &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/correios-lanca-selo-comemorativo-em-homenagem-ao-papa-francisco\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Correios lan\u00e7a selo comemorativo em homenagem ao Papa Francisco&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5673","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5673"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5673\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}