{"id":5683,"date":"2020-11-10T11:20:45","date_gmt":"2020-11-10T11:20:45","guid":{"rendered":"https:\/\/www.brindice.com.br\/blog\/marketing-de-atribuicao-resultados-para-sua-campanha-digital\/"},"modified":"2020-11-10T11:20:45","modified_gmt":"2020-11-10T11:20:45","slug":"marketing-de-atribuicao-resultados-para-sua-campanha-digital","status":"publish","type":"post","link":"https:\/\/www.brindice.com.br\/blog\/marketing-de-atribuicao-resultados-para-sua-campanha-digital\/","title":{"rendered":"Marketing de Atribui\u00e7\u00e3o: Resultados para sua Campanha Digital"},"content":{"rendered":"<p>O crescimento cont\u00ednuo do n\u00famero de pessoas que acessam a internet e as redes sociais tem incentivado muitas empresas de diferentes setores a realizarem campanhas de comunica\u00e7\u00e3o nos mais diversos meios digitais: portais, sites de nicho, links patrocinados nos buscadores, blogs e nas redes sociais.<br \/>\nA vantagem de uma campanha de marketing digital \u00e9 a possibilidade de obter as informa\u00e7\u00f5es sobre os resultados de cada um dos diferentes meios, ve\u00edculos, canais e formatos, como a entrega de impress\u00f5es, cliques, taxa de clique, taxa de convers\u00e3o, entre outras.<\/p>\n<p>Por\u00e9m, essas informa\u00e7\u00f5es n\u00e3o s\u00e3o integradas, o que pode acarretar an\u00e1lises equivocadas ao se atribuir todo o retorno obtido apenas ao ve\u00edculo que gerou a convers\u00e3o final do cliente, sendo essa convers\u00e3o uma venda, um cadastro ou mesmo a forma\u00e7\u00e3o de uma comunidade engajada na sua marca.  Para n\u00e3o cair neste erro, o ideal \u00e9 mapear os pontos de contato do cliente com a sua campanha online durante seu caminho para a convers\u00e3o e assim saber, de maneira precisa, como as a\u00e7\u00f5es nos diferentes ve\u00edculos e formatos est\u00e3o impactando o seu p\u00fablico alvo, quais est\u00e3o gerando mais convers\u00f5es e devem receber um volume maior de recursos e investimento.<\/p>\n<p>Portanto, a integra\u00e7\u00e3o das informa\u00e7\u00f5es de sua campanha online \u00e9 essencial. Para isso, \u00e9 preciso investir numa ferramenta de Digital Marketing Suite (DMS), que \u00e9 um m\u00e9todo centralizado que permite medir de que forma cada usu\u00e1rio foi impactado e quanto cada ve\u00edculo e formato contribu\u00edram para a convers\u00e3o do cliente, al\u00e9m da personaliza\u00e7\u00e3o da comunica\u00e7\u00e3o em fun\u00e7\u00e3o do seu comportamento e interesse. Um bom exemplo dessa ferramenta \u00e9 a empresa IgnitionOne, h\u00e1 pouco tempo no Brasil, mas que j\u00e1 demonstra a que veio, atrav\u00e9s de muitos cases interessantes, como da concession\u00e1ria GM.<\/p>\n<p>Exemplo: uma cliente encontra seu site clicando em um link patrocinado. Ela volta uma semana depois clicando em uma rede social. Nesse mesmo dia, ela recebe um email e volta pela terceira vez para o seu site, agora com uma possibilidade maior de convers\u00e3o, na vis\u00e3o da ferramenta que calcula a pretens\u00e3o do usu\u00e1rio para a compra. Ainda assim, n\u00e3o faz a compra. Como a ferramenta sabe o produto de interesse desta cliente, \u00e9 poss\u00edvel gerar um banner com uma promo\u00e7\u00e3o desse produto em um site qualquer que ela acesse. Mais uma vez ela \u00e9 impactada, entra no site e finalmente realiza a compra.<\/p>\n<p>Na pr\u00e1tica n\u00e3o \u00e9 apenas um ve\u00edculo ou formato que proporcionou a convers\u00e3o, conforme o exemplo apresentado, mas cada um dos pontos de contato com a campanha online teve sua parcela de contribui\u00e7\u00e3o. Afinal, o \u00faltimo clique no banner poderia n\u00e3o ter ocorrido se n\u00e3o houvesse uma conhecimento adquirido sobre o produto de interesse e o est\u00e1gio de compra desta usu\u00e1ria, de modo a reconhecer o momento apropriado para fazer uma oferta diferenciada. Tudo isso s\u00f3 foi poss\u00edvel devido \u00e0 integra\u00e7\u00e3o e centraliza\u00e7\u00e3o dos conhecimentos obtidos durante o processo.<br \/>\nEsse conhecimento permite desenvolver campanhas online baseadas na experi\u00eancia de cada usu\u00e1rio (engajamento), o que pode ser chamado de atribui\u00e7\u00e3o de comportamento ou marketing de atribui\u00e7\u00e3o, e, consequentemente, obter melhores resultados e rentabilizar o investimento ao destinar para cada ve\u00edculo e formato o correspondente ao seu peso de contribui\u00e7\u00e3o para o caminho de convers\u00e3o, al\u00e9m do desenvolvimento de uma comunica\u00e7\u00e3o mais personalizada e adequada ao est\u00e1gio de compra.<\/p>\n<p>\u00c9 por conta dessa sofistica\u00e7\u00e3o que o marketing de atribui\u00e7\u00e3o tem se tornado a \u00faltima palavra quando o assunto \u00e9 Marketing no mundo digital.<\/p>\n<p>Sandra Turchi \u00e9 consultora e palestrante sobre em Marketing Digital e E-commerce. Leciona no MBA da FGV em Marketing Digital e coordena diversos cursos na \u00e1rea digital da ESPM-SP. Atua como profissional de Marketing h\u00e1 mais de 20 anos onde foi executiva de grandes empresas. Bacharel em Administra\u00e7\u00e3o de Empresas pela FEA\/USP, p\u00f3s-graduada pela FGV\/EAESP, possui MBA pela Business School SP com a Toronto University e estudou empreendedorismo na Babson College de Boston.  <\/p>\n<p>Fonte: Cidade MArketing<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O crescimento cont\u00ednuo do n\u00famero de pessoas que acessam a internet e as redes sociais tem incentivado muitas empresas de diferentes setores a realizarem campanhas de comunica\u00e7\u00e3o nos mais diversos meios digitais: portais, sites de nicho, links patrocinados nos buscadores, blogs e nas redes sociais. A vantagem de uma campanha de marketing digital \u00e9 a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brindice.com.br\/blog\/marketing-de-atribuicao-resultados-para-sua-campanha-digital\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Marketing de Atribui\u00e7\u00e3o: Resultados para sua Campanha Digital&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5683","post","type-post","status-publish","format-standard","hentry","category-marketing-promocional"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5683"}],"version-history":[{"count":0,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/posts\/5683\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brindice.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}